{"id":1191,"date":"2024-03-14T15:59:34","date_gmt":"2024-03-14T15:59:34","guid":{"rendered":"https:\/\/marina-clavet-coaching.com\/datenschutz\/"},"modified":"2024-03-14T15:59:34","modified_gmt":"2024-03-14T15:59:34","slug":"datenschutz","status":"publish","type":"page","link":"https:\/\/marina-clavet-coaching.com\/en\/datenschutz\/","title":{"rendered":"Datenschutz"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;FAQ&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;|auto||176px||&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<div>\n<div><\/div>\n<\/div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<h2 class=\"wp-block-heading\">Datenschutzerkl\u00e4rung<\/h2>\n<p>Personenbezogene Daten (nachfolgend zumeist nur \u201eDaten\u201c genannt) werden von uns nur im Rahmen der Erforderlichkeit sowie zum Zwecke der Bereitstellung eines funktionsf\u00e4higen und nutzerfreundlichen Internetauftritts, inklusive seiner Inhalte und der dort angebotenen Leistungen, verarbeitet.<\/p>\n<p>Gem\u00e4\u00df Art. 4 Ziffer 1. der Verordnung (EU) 2016\/679, also der Datenschutz-Grundverordnung (nachfolgend nur \u201eDSGVO\u201c genannt), gilt als \u201eVerarbeitung\u201c jeder mit oder ohne Hilfe automatisierter Verfahren ausgef\u00fchrter Vorgang oder jede solche Vorgangsreihe im Zusammenhang mit personenbezogenen Daten, wie das Erheben, das Erfassen, die Organisation, das Ordnen, die Speicherung, die Anpassung oder Ver\u00e4nderung, das Auslesen, das Abfragen, die Verwendung, die Offenlegung durch \u00dcbermittlung, Verbreitung oder eine andere Form der Bereitstellung, den Abgleich oder die Verkn\u00fcpfung, die Einschr\u00e4nkung, das L\u00f6schen oder die Vernichtung.<\/p>\n<p>Mit der nachfolgenden Datenschutzerkl\u00e4rung informieren wir Sie insbesondere \u00fcber Art, Umfang, Zweck, Dauer und Rechtsgrundlage der Verarbeitung personenbezogener Daten, soweit wir entweder allein oder gemeinsam mit anderen \u00fcber die Zwecke und Mittel der Verarbeitung entscheiden. Zudem informieren wir Sie nachfolgend \u00fcber die von uns zu Optimierungszwecken sowie zur Steigerung der Nutzungsqualit\u00e4t eingesetzten Fremdkomponenten, soweit hierdurch Dritte Daten in wiederum eigener Verantwortung verarbeiten.<\/p>\n<p>Unsere Datenschutzerkl\u00e4rung ist wie folgt gegliedert:<\/p>\n<p>I. Informationen \u00fcber uns als Verantwortliche<br \/>II. Rechte der Nutzer und Betroffenen<br \/>III. Informationen zur Datenverarbeitung<\/p>\n<h3 class=\"wp-block-heading\">I. Informationen \u00fcber uns als Verantwortliche<\/h3>\n<p>Verantwortlicher Anbieter dieses Internetauftritts im datenschutzrechtlichen Sinne ist:<\/p>\n<h3><span>Follow your dream<\/span><br \/><span>Marina, Clavet<\/span><br \/><span>Loisachstrasse 3<\/span><br \/><span>82418 Murnau<\/span><\/h3>\n<p>Telefon: 0176 49676 1001<br \/>Telefax: [Faxnummer]<br \/>E-Mail: contact@marina-clavet-coaching.com<\/p>\n<h3><\/h3>\n<h3 class=\"wp-block-heading\">II. Rechte der Nutzer und Betroffenen<\/h3>\n<p>Mit Blick auf die nachfolgend noch n\u00e4her beschriebene Datenverarbeitung haben die Nutzer und Betroffenen das Recht<\/p>\n<ul>\n<li>auf Best\u00e4tigung, ob sie betreffende Daten verarbeitet werden, auf Auskunft \u00fcber die verarbeiteten Daten, auf weitere Informationen \u00fcber die Datenverarbeitung sowie auf Kopien der Daten (vgl. auch Art. 15 DSGVO);<\/li>\n<li>auf Berichtigung oder Vervollst\u00e4ndigung unrichtiger bzw. unvollst\u00e4ndiger Daten (vgl. auch Art. 16 DSGVO);<\/li>\n<li>auf unverz\u00fcgliche L\u00f6schung der sie betreffenden Daten (vgl. auch Art. 17 DSGVO), oder, alternativ, soweit eine weitere Verarbeitung gem\u00e4\u00df Art. 17 Abs. 3 DSGVO erforderlich ist, auf Einschr\u00e4nkung der Verarbeitung nach Ma\u00dfgabe von Art. 18 DSGVO;<\/li>\n<li>auf Erhalt der sie betreffenden und von ihnen bereitgestellten Daten und auf \u00dcbermittlung dieser Daten an andere Anbieter\/Verantwortliche (vgl. auch Art. 20 DSGVO);<\/li>\n<li>auf Beschwerde gegen\u00fcber der Aufsichtsbeh\u00f6rde, sofern sie der Ansicht sind, dass die sie betreffenden Daten durch den Anbieter unter Versto\u00df gegen datenschutzrechtliche Bestimmungen verarbeitet werden (vgl. auch Art. 77 DSGVO).<\/li>\n<\/ul>\n<p>Dar\u00fcber hinaus ist der Anbieter dazu verpflichtet, alle Empf\u00e4nger, denen gegen\u00fcber Daten durch den Anbieter offengelegt worden sind, \u00fcber jedwede Berichtigung oder L\u00f6schung von Daten oder die Einschr\u00e4nkung der Verarbeitung, die aufgrund der Artikel 16, 17 Abs. 1, 18 DSGVO erfolgt, zu unterrichten. Diese Verpflichtung besteht jedoch nicht, soweit diese Mitteilung unm\u00f6glich oder mit einem unverh\u00e4ltnism\u00e4\u00dfigen Aufwand verbunden ist. Unbeschadet dessen hat der Nutzer ein Recht auf Auskunft \u00fcber diese Empf\u00e4nger.<\/p>\n<p><strong>Ebenfalls haben die Nutzer und Betroffenen nach Art. 21 DSGVO das Recht auf Widerspruch gegen die k\u00fcnftige Verarbeitung der sie betreffenden Daten, sofern die Daten durch den Anbieter nach Ma\u00dfgabe von Art. 6 Abs. 1 lit. f) DSGVO verarbeitet werden. Insbesondere ist ein Widerspruch gegen die Datenverarbeitung zum Zwecke der Direktwerbung statthaft.<\/strong><\/p>\n<h3 class=\"wp-block-heading\">III. Informationen zur Datenverarbeitung<\/h3>\n<p>Ihre bei Nutzung unseres Internetauftritts verarbeiteten Daten werden gel\u00f6scht oder gesperrt, sobald der Zweck der Speicherung entf\u00e4llt, der L\u00f6schung der Daten keine gesetzlichen Aufbewahrungspflichten entgegenstehen und nachfolgend keine anderslautenden Angaben zu einzelnen Verarbeitungsverfahren gemacht werden.<\/p>\n<h4 class=\"jet-listing-dynamic-field__content\">Kontaktanfragen \/ Kontaktm\u00f6glichkeit<\/h4>\n<p>Sofern Sie per Kontaktformular oder E-Mail mit uns in Kontakt treten, werden die dabei von Ihnen angegebenen Daten zur Bearbeitung Ihrer Anfrage genutzt. Die Angabe der Daten ist zur Bearbeitung und Beantwortung Ihre Anfrage erforderlich \u2013 ohne deren Bereitstellung k\u00f6nnen wir Ihre Anfrage nicht oder allenfalls eingeschr\u00e4nkt beantworten.<\/p>\n<p>Rechtsgrundlage f\u00fcr diese Verarbeitung ist Art. 6 Abs. 1 lit. b) DSGVO.<\/p>\n<p>Ihre Daten werden gel\u00f6scht, sofern Ihre Anfrage abschlie\u00dfend beantwortet worden ist und der L\u00f6schung keine gesetzlichen Aufbewahrungspflichten entgegenstehen, wie bspw. bei einer sich etwaig anschlie\u00dfenden Vertragsabwicklung.<\/p>\n<h4 class=\"jet-listing-dynamic-field__content\">Serverdaten<\/h4>\n<p>Aus technischen Gr\u00fcnden, insbesondere zur Gew\u00e4hrleistung eines sicheren und stabilen Internetauftritts, werden Daten durch Ihren Internet-Browser an uns bzw. an unseren Webspace-Provider \u00fcbermittelt. Mit diesen sog. Server-Logfiles werden u.a. Typ und Version Ihres Internetbrowsers, das Betriebssystem, die Website, von der aus Sie auf unseren Internetauftritt gewechselt haben (Referrer URL), die Website(s) unseres Internetauftritts, die Sie besuchen, Datum und Uhrzeit des jeweiligen Zugriffs sowie die IP-Adresse des Internetanschlusses, von dem aus die Nutzung unseres Internetauftritts erfolgt, erhoben.<\/p>\n<p>Diese so erhobenen Daten werden vorr\u00fcbergehend gespeichert, dies jedoch nicht gemeinsam mit anderen Daten von Ihnen.<\/p>\n<p>Diese Speicherung erfolgt auf der Rechtsgrundlage von Art. 6 Abs. 1 lit. f) DSGVO. Unser berechtigtes Interesse liegt in der Verbesserung, Stabilit\u00e4t, Funktionalit\u00e4t und Sicherheit unseres Internetauftritts.<\/p>\n<p>Die Daten werden sp\u00e4testens nach sieben Tage wieder gel\u00f6scht, soweit keine weitere Aufbewahrung zu Beweiszwecken erforderlich ist. Andernfalls sind die Daten bis zur endg\u00fcltigen Kl\u00e4rung eines Vorfalls ganz oder teilweise von der L\u00f6schung ausgenommen.<\/p>\n<h4 class=\"jet-listing-dynamic-field__content\">Facebook<\/h4>\n<p>Zur Bewerbung unserer Produkte und Leistungen sowie zur Kommunikation mit Interessenten oder Kunden betreiben wir eine Firmenpr\u00e4senz auf der Plattform Facebook.<\/p>\n<p>Auf dieser Social-Media-Plattform sind wir gemeinsam mit der Meta Platforms Ireland Limited, 4 Grand Canal Square, Dublin 2, Irland, verantwortlich.<\/p>\n<p>Der Datenschutzbeauftragte von Facebook kann \u00fcber ein Kontaktformular erreicht werden:<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/help\/contact\/540977946302970\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/www.facebook.com\/help\/contact\/540977946302970<\/a><\/p>\n<p>Die gemeinsame Verantwortlichkeit haben wir in einer Vereinbarung bez\u00fcglich der jeweiligen Verpflichtungen im Sinne der DSGVO geregelt. Diese Vereinbarung, aus der sich die gegenseitigen Verpflichtungen ergeben, ist unter dem folgenden Link abrufbar:<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/legal\/terms\/page_controller_addendum\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/www.facebook.com\/legal\/terms\/page_controller_addendum<\/a><\/p>\n<p>Rechtsgrundlage f\u00fcr die dadurch erfolgende und nachfolgend wiedergegebene Verarbeitung von personenbezogenen Daten ist Art. 6 Abs. 1 lit. f DSGVO. Unser berechtigtes Interesse besteht an der Analyse, der Kommunikation sowie dem Absatz und der Bewerbung unserer Produkte und Leistungen.<\/p>\n<p>Rechtsgrundlage kann auch eine Einwilligung des Nutzers gem\u00e4\u00df Art. 6 Abs. 1 lit. a DSGVO gegen\u00fcber dem Plattformbetreiber sein. Die Einwilligung hierzu kann der Nutzer nach Art. 7 Abs. 3 DSGVO jederzeit durch eine Mitteilung an den Plattformbetreiber f\u00fcr die Zukunft widerrufen.<\/p>\n<p>Bei dem Aufruf unseres Onlineauftritts auf der Plattform Facebook werden von der Facebook Ireland Ltd. als Betreiberin der Plattform in der EU Daten des Nutzers (z.B. pers\u00f6nliche Informationen, IP-Adresse etc.) verarbeitet.<\/p>\n<p>Diese Daten des Nutzers dienen zu statistischen Informationen \u00fcber die Inanspruchnahme unserer Firmenpr\u00e4senz auf Facebook. Die Facebook Ireland Ltd. nutzt diese Daten zu Marktforschungs- und Werbezwecken sowie zur Erstellung von Profilen der Nutzer. Anhand dieser Profile ist es der Facebook Ireland Ltd. beispielsweise m\u00f6glich, die Nutzer innerhalb und au\u00dferhalb von Facebook interessenbezogen zu bewerben. Ist der Nutzer zum Zeitpunkt des Aufrufes in seinem Account auf Facebook eingeloggt, kann die Facebook Ireland Ltd. zudem die Daten mit dem jeweiligen Nutzerkonto verkn\u00fcpfen.<\/p>\n<p>Im Falle einer Kontaktaufnahme des Nutzers \u00fcber Facebook werden die bei dieser Gelegenheit eingegebenen personenbezogenen Daten des Nutzers zur Bearbeitung der Anfrage genutzt. Die Daten des Nutzers werden bei uns gel\u00f6scht, sofern die Anfrage des Nutzers abschlie\u00dfend beantwortet wurde und keine gesetzlichen Aufbewahrungspflichten, wie z.B. bei einer anschlie\u00dfenden Vertragsabwicklung, entgegenstehen.<\/p>\n<p>Zur Verarbeitung der Daten werden von der Facebook Ireland Ltd. ggf. auch Cookies gesetzt.<\/p>\n<p>Sollte der Nutzer mit dieser Verarbeitung nicht einverstanden sein, so besteht die M\u00f6glichkeit, die Installation der Cookies durch eine entsprechende Einstellung des Browsers zu verhindern. Bereits gespeicherte Cookies k\u00f6nnen ebenfalls jederzeit gel\u00f6scht werden. Die Einstellungen hierzu sind vom jeweiligen Browser abh\u00e4ngig. Bei Flash-Cookies l\u00e4sst sich die Verarbeitung nicht \u00fcber die Einstellungen des Browsers unterbinden, sondern durch die entsprechende Einstellung des Flash-Players. Sollte der Nutzer die Installation der Cookies verhindern oder einschr\u00e4nken, kann dies dazu f\u00fchren, dass nicht s\u00e4mtliche Funktionen von Facebook vollumf\u00e4nglich nutzbar sind.<\/p>\n<p>N\u00e4heres zu den Verarbeitungst\u00e4tigkeiten, deren Unterbindung und zur L\u00f6schung der von Facebook verarbeiteten Daten finden sich in der Datenrichtlinie von Facebook:<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/privacy\/explanation\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/www.facebook.com\/privacy\/explanation<\/a><\/p>\n<p>Es ist nicht ausgeschlossen, dass die Verarbeitung durch die Meta Platforms Ireland Limited auch \u00fcber die Meta Platforms, Inc., 1601 Willow Road, Menlo Park, California 94025 in den USA erfolgt.<\/p>\n<h4 class=\"jet-listing-dynamic-field__content\">Instagram<\/h4>\n<p>Zur Bewerbung unserer Produkte und Leistungen sowie zur Kommunikation mit Interessenten oder Kunden betreiben wir eine Firmenpr\u00e4senz auf der Plattform Instagram.<\/p>\n<p>Auf dieser Social-Media-Plattform sind wir gemeinsam mit der Meta Platforms Ireland Limited, 4 Grand Canal Square, Dublin 2, Irland, verantwortlich.<\/p>\n<p>Der Datenschutzbeauftragte von Instagram kann \u00fcber ein Kontaktformular erreicht werden:<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/help\/contact\/540977946302970\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/www.facebook.com\/help\/contact\/540977946302970<\/a><\/p>\n<p>Die gemeinsame Verantwortlichkeit haben wir in einer Vereinbarung bez\u00fcglich der jeweiligen Verpflichtungen im Sinne der DSGVO geregelt. Diese Vereinbarung, aus der sich die gegenseitigen Verpflichtungen ergeben, ist unter dem folgenden Link abrufbar:<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/legal\/terms\/page_controller_addendum\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/www.facebook.com\/legal\/terms\/page_controller_addendum<\/a><\/p>\n<p>Rechtsgrundlage f\u00fcr die dadurch erfolgende und nachfolgend wiedergegebene Verarbeitung von personenbezogenen Daten ist Art. 6 Abs. 1 lit. f DSGVO. Unser berechtigtes Interesse besteht an der Analyse, der Kommunikation sowie dem Absatz und der Bewerbung unserer Produkte und Leistungen.<\/p>\n<p>Rechtsgrundlage kann auch eine Einwilligung des Nutzers gem\u00e4\u00df Art. 6 Abs. 1 lit. a DSGVO gegen\u00fcber dem Plattformbetreiber sein. Die Einwilligung hierzu kann der Nutzer nach Art. 7 Abs. 3 DSGVO jederzeit durch eine Mitteilung an den Plattformbetreiber f\u00fcr die Zukunft widerrufen.<\/p>\n<p>Bei dem Aufruf unseres Onlineauftritts auf der Plattform Instagram werden von der Facebook Ireland Ltd. als Betreiberin der Plattform in der EU Daten des Nutzers (z.B. pers\u00f6nliche Informationen, IP-Adresse etc.) verarbeitet.<\/p>\n<p>Diese Daten des Nutzers dienen zu statistischen Informationen \u00fcber die Inanspruchnahme unserer Firmenpr\u00e4senz auf Instagram. Die Facebook Ireland Ltd. nutzt diese Daten zu Marktforschungs- und Werbezwecken sowie zur Erstellung von Profilen der Nutzer. Anhand dieser Profile ist es der Facebook Ireland Ltd. beispielsweise m\u00f6glich, die Nutzer innerhalb und au\u00dferhalb von Instagram interessenbezogen zu bewerben. Ist der Nutzer zum Zeitpunkt des Aufrufes in seinem Account auf Instagram eingeloggt, kann die Facebook Ireland Ltd. zudem die Daten mit dem jeweiligen Nutzerkonto verkn\u00fcpfen.<\/p>\n<p>Im Falle einer Kontaktaufnahme des Nutzers \u00fcber Instagram werden die bei dieser Gelegenheit eingegebenen personenbezogenen Daten des Nutzers zur Bearbeitung der Anfrage genutzt. Die Daten des Nutzers werden bei uns gel\u00f6scht, sofern die Anfrage des Nutzers abschlie\u00dfend beantwortet wurde und keine gesetzlichen Aufbewahrungspflichten, wie z.B. bei einer anschlie\u00dfenden Vertragsabwicklung, entgegenstehen.<\/p>\n<p>Zur Verarbeitung der Daten werden von der Facebook Ireland Ltd. ggf. auch Cookies gesetzt.<\/p>\n<p>Sollte der Nutzer mit dieser Verarbeitung nicht einverstanden sein, so besteht die M\u00f6glichkeit, die Installation der Cookies durch eine entsprechende Einstellung des Browsers zu verhindern. Bereits gespeicherte Cookies k\u00f6nnen ebenfalls jederzeit gel\u00f6scht werden. Die Einstellungen hierzu sind vom jeweiligen Browser abh\u00e4ngig. Bei Flash-Cookies l\u00e4sst sich die Verarbeitung nicht \u00fcber die Einstellungen des Browsers unterbinden, sondern durch die entsprechende Einstellung des Flash-Players. Sollte der Nutzer die Installation der Cookies verhindern oder einschr\u00e4nken, kann dies dazu f\u00fchren, dass nicht s\u00e4mtliche Funktionen von Facebook vollumf\u00e4nglich nutzbar sind.<\/p>\n<p>N\u00e4heres zu den Verarbeitungst\u00e4tigkeiten, deren Unterbindung und zur L\u00f6schung der von Instagram verarbeiteten Daten finden sich in der Datenrichtlinie von Instagram:<\/p>\n<p><a href=\"https:\/\/help.instagram.com\/519522125107875\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/help.instagram.com\/519522125107875<\/a><\/p>\n<p>Es ist nicht ausgeschlossen, dass die Verarbeitung durch die Facebook Ireland Ltd. auch \u00fcber die Meta Platforms, Inc., 1601 Willow Road, Menlo Park, California 94025 in den USA erfolgt.<\/p>\n<h4 class=\"jet-listing-dynamic-field__content\">LinkedIn<\/h4>\n<p>Wir unterhalten bei LinkedIn eine Onlinepr\u00e4senz um unser Unternehmen sowie unsere Leistungen zu pr\u00e4sentieren und mit Kunden\/Interessenten zu kommunizieren. LinkedIn ist ein Service der LinkedIn Ireland Unlimited Company, Wilton Plaza, Wilton Place, Dublin 2, Irland, ein Tochterunternehmen der LinkedIn Corporation, 1000 W. Maude Avenue, Sunnyvale, CA 94085, USA.<\/p>\n<p>Insofern weisen wir darauf hin, dass die M\u00f6glichkeit besteht, dass Daten der Nutzer au\u00dferhalb der Europ\u00e4ischen Union, insbesondere in den USA, verarbeitet werden. Hierdurch k\u00f6nnen gesteigerte Risiken f\u00fcr die Nutzer insofern bestehen, als dass z.B. der sp\u00e4tere Zugriff auf die Nutzerdaten erschwert werden kann. Auch haben wir keinen Zugriff auf diese Nutzerdaten. Die Zugriffsm\u00f6glichkeit liegt ausschlie\u00dflich bei LinkedIn.<\/p>\n<p>Die Datenschutzhinweise von LinkedIn finden Sie unter<\/p>\n<p><a href=\"https:\/\/www.linkedin.com\/legal\/privacy-policy\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/www.linkedin.com\/legal\/privacy-policy<\/a><\/p>\n<h4 class=\"jet-listing-dynamic-field__content\">YouTube<\/h4>\n<p>Wir unterhalten bei YouTube eine Onlinepr\u00e4senz um unser Unternehmen sowie unsere Leistungen zu pr\u00e4sentieren und mit Kunden\/Interessenten zu kommunizieren. YouTube ist ein Service der Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irland, ein Tochterunternehmen der Google LLC, 1600 Amphitheatre Parkway, Mountain View, CA 94043 USA.<\/p>\n<p>Insofern weisen wir darauf hin, dass die M\u00f6glichkeit besteht, dass Daten der Nutzer au\u00dferhalb der Europ\u00e4ischen Union, insbesondere in den USA, verarbeitet werden. Hierdurch k\u00f6nnen gesteigerte Risiken f\u00fcr die Nutzer insofern bestehen, als dass z.B. der sp\u00e4tere Zugriff auf die Nutzerdaten erschwert werden kann. Auch haben wir keinen Zugriff auf diese Nutzerdaten. Die Zugriffsm\u00f6glichkeit liegt ausschlie\u00dflich bei YouTube.<\/p>\n<p>Die Datenschutzhinweise von YouTube finden Sie unter<\/p>\n<p><a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/policies.google.com\/privacy<\/a><\/p>\n<h4 class=\"jet-listing-dynamic-field__content\">facebook<\/h4>\n<p>Meta Platforms Ireland Limited, 4 Grand Canal Square, Dublin 2, Irland.<\/p>\n<p>Datenschutzerkl\u00e4rung: <a href=\"https:\/\/www.facebook.com\/policy.php\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/www.facebook.com\/policy.php<\/a><\/p>\n<h4 class=\"jet-listing-dynamic-field__content\">Instagram<\/h4>\n<p>Meta Platforms Ireland Limited, 4 Grand Canal Square, Dublin 2, Irland.<\/p>\n<p>Datenschutzerkl\u00e4rung: <a href=\"https:\/\/help.instagram.com\/519522125107875\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/help.instagram.com\/519522125107875<\/a><\/p>\n<h4 class=\"jet-listing-dynamic-field__content\">LinkedIn<\/h4>\n<p>LinkedIn Ireland Unlimited Company, Wilton Plaza, Wilton Place, Dublin 2, Irland, ein Tochterunternehmen der LinkedIn Corporation, 1000 W. Maude Avenue, Sunnyvale, CA 94085 USA.<\/p>\n<p>Datenschutzerkl\u00e4rung: <a href=\"https:\/\/www.linkedin.com\/legal\/privacy-policy\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/www.linkedin.com\/legal\/privacy-policy<\/a><\/p>\n<h4 class=\"jet-listing-dynamic-field__content\">YouTube<\/h4>\n<p>Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irland, ein Tochterunternehmen der Google LLC, 1600 Amphitheatre Parkway, Mountain View, CA 94043 USA<\/p>\n<p>Datenschutzerkl\u00e4rung: <a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/policies.google.com\/privacy<\/a><\/p>\n<h4 class=\"jet-listing-dynamic-field__content\">IONOS Tracking MYWEBSITE<\/h4>\n<p>In unserem Internetauftritt setzen wir MyWebsite ein. Hierbei handelt es sich um einen Dienst der 1&amp;1 IONOS SE, Elgendorfer Str. 57, 56410 Montabaur, nachfolgend nur \u201eMyWebsite\u201c genannt.<\/p>\n<p>Durch MyWebsite werden Tracking-Cookies \u00fcber Ihren Internet-Browser Cookies auf Ihrem Endger\u00e4t gespeichert, die auf der Technologie Snowplow Analytics von der Snowplow Analytics Limited, 32-38, Scrutton Street, London, Gro\u00dfbritannien, basieren. Mit Hilfe dieser Cookies kann z. B. ausgewertet werden, wie h\u00e4ufig Sie unseren Internetauftritt besuchen oder welche (Unter-) Seiten unseres Internetauftritts aufgerufen werden. Die 1&amp;1 IONOS SE gibt hierzu an, dass dabei keinerlei personenbezogene Daten erfasst w\u00fcrden.<\/p>\n<p>Im Falle einer von Ihnen erteilten Einwilligung f\u00fcr diese Verarbeitung ist Rechtsgrundlage Art. 6 Abs. 1 lit. a DSGVO. Rechtsgrundlage kann auch Art. 6 Abs. 1 lit. f DSGVO sein. Unser berechtigtes Interesse liegt in der Verbesserung und Optimierung unseres Internetauftritts.<\/p>\n<p>Falls Sie mit dieser Verarbeitung nicht einverstanden sind, haben Sie die M\u00f6glichkeit, die Speicherung der Cookies durch eine Einstellung in Ihrem Internet-Browsers zu verhindern. N\u00e4here Informationen hierzu finden Sie vorstehend unter \u201eCookies\u201c.<\/p>\n<h4 class=\"jet-listing-dynamic-field__content\">IONOS WebAnalytics<\/h4>\n<p>In unserem Internetauftritt setzen wir WebAnalytics ein. Hierbei handelt es sich um einen Analyse-Dienst der 1&amp;1 IONOS SE, Elgendorfer Str. 57, 56410 Montabaur, Deutschland, nachfolgend nur \u201eWebAnalytics\u201c genannt, mit dem wir die Benutzung unseres Internetauftritts analysieren k\u00f6nnen.<\/p>\n<p>Zur Analyse werden anhand eines Pixels oder \u00fcber die Logfiles in unserem Auftrag Daten \u00fcber Typ und Version Ihres Internetbrowsers, Ihr Betriebssystem, der Typ Ihres Endger\u00e4tes, die Website, von der aus Sie auf unseren Internetauftritt gewechselt haben (Referrer URL), die Website(s) unseres Internetauftritts, die Sie besuchen, oder die Dateien, die Sie anfordern, Datum und Uhrzeit des jeweiligen Zugriffs sowie die anonymisierte IP-Adresse des Internetanschlusses, von dem aus die Nutzung unseres Internetauftritts erfolgt, erhoben.<\/p>\n<p>Im Falle einer von Ihnen erteilten Einwilligung f\u00fcr diese Verarbeitung ist Rechtsgrundlage Art. 6 Abs. 1 lit. a DSGVO. Rechtsgrundlage kann auch Art. 6 Abs. 1 lit. f DSGVO sein. Unser berechtigtes Interesse liegt in der Analyse, Optimierung, Verbesserung sowie in dem wirtschaftlichen Betrieb unseres Internetauftritts.<\/p>\n<h4 class=\"jet-listing-dynamic-field__content\">Google Fonts<\/h4>\n<p>In unserem Internetauftritt setzen wir Google Fonts zur Darstellung externer Schriftarten ein. Es handelt sich hierbei um einen Dienst der Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irland, nachfolgend nur \u201eGoogle\u201c genannt.<\/p>\n<p>Um die Darstellung bestimmter Schriften in unserem Internetauftritt zu erm\u00f6glichen, wird bei Aufruf unseres Internetauftritts eine Verbindung zu dem Google-Server in den USA aufgebaut.<\/p>\n<p>Rechtsgrundlage ist Art. 6 Abs. 1 lit. f) DSGVO. Unser berechtigtes Interesse liegt in der Optimierung und dem wirtschaftlichen Betrieb unseres Internetauftritts.<\/p>\n<p>Durch die bei Aufruf unseres Internetauftritts hergestellte Verbindung zu Google kann Google ermitteln, von welcher Website Ihre Anfrage gesendet worden ist und an welche IP-Adresse die Darstellung der Schrift zu \u00fcbermitteln ist.<\/p>\n<p>Google bietet unter<\/p>\n<p><a href=\"https:\/\/adssettings.google.com\/authenticated\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/adssettings.google.com\/authenticated<\/a><\/p>\n<p><a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/policies.google.com\/privacy<\/a><\/p>\n<p>weitere Informationen an und zwar insbesondere zu den M\u00f6glichkeiten der Unterbindung der Datennutzung.<\/p>\n<h4 class=\"jet-listing-dynamic-field__content\">mywebsite-editor.com \u2013 1&amp;1 IONOS SE<\/h4>\n<p>Zur Funktionalit\u00e4t unseres Internetauftritts setzen wir den Dienst mywebsite-editor.com ein. Hierbei handelt es sich um einen Dienst der 1&amp;1 IONOS SE, Elgendorfer Str. 57, 56410 Montabaur, Deutschland, nachfolgend nur \u201emywebsite-editor\u201c genannt.<\/p>\n<p>Aufgrund des Einbindens von mywebsite-editor l\u00e4dt Ihr Internet-Browser zur Darstellung der Inhalte unseres Internetauftritts einen zwingend ben\u00f6tigten Java-Script-Code von dem mywebsite-editor Server. Hierdurch erlangt mywebsite-editor Kenntnis davon, dass unser Internetauftritt \u00fcber Ihre IP-Adresse aufgerufen worden ist. Gleichzeitig wird ein sog. Session-Cookie \u00fcber Ihren Internet-Browser auf Ihrem Endger\u00e4t gespeichert.<\/p>\n<p>Rechtsgrundlage f\u00fcr die Datenverarbeitung ist Art. 6 Abs.1 lit. f) DSGVO. Unser berechtigtes Interesse liegt in der Pr\u00e4sentation einer einheitlichen und ansprechenden Darstellung unseres Internetauftritts.<\/p>\n<p>Um die Ausf\u00fchrung des Java-Script-Codes von mywebsite-editor und dadurch die Erfassung sowie die Verarbeitung Ihrer Daten zu verhindern, k\u00f6nnen Sie einen sog. Java-Script-Blocker installieren, wie bspw. noscript.net oder ghostery.com. Zudem k\u00f6nnen Sie die Ausf\u00fchrung des Java-Script-Codes in den Einstellungen Ihres Internet-Browsers deaktivieren.<\/p>\n<p>Falls Sie mit der Verarbeitung der Cookies nicht einverstanden sind, haben Sie die M\u00f6glichkeit, auch die Speicherung der Cookies durch eine Einstellung in Ihrem Internet-Browsers zu verhindern. N\u00e4here Informationen hierzu finden Sie vorstehend unter \u201eCookies\u201c.<\/p>\n<p><a href=\"https:\/\/www.xn--generator-datenschutzerklrung-pqc.de\/\" target=\"_blank\" rel=\"noopener\">Muster-Datenschutzerkl\u00e4rung<\/a> der <a href=\"https:\/\/www.ratgeberrecht.eu\/datenschutz\/datenschutzerklaerung-generator-dsgvo.html\" target=\"_blank\" rel=\"noopener\">Anwaltskanzlei Wei\u00df &amp; Partner<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Datenschutzerkl\u00e4rung Personenbezogene Daten (nachfolgend zumeist nur \u201eDaten\u201c genannt) werden von uns nur im Rahmen der Erforderlichkeit sowie zum Zwecke der Bereitstellung eines funktionsf\u00e4higen und nutzerfreundlichen Internetauftritts, inklusive seiner Inhalte und der dort angebotenen Leistungen, verarbeitet. Gem\u00e4\u00df Art. 4 Ziffer 1. der Verordnung (EU) 2016\/679, also der Datenschutz-Grundverordnung (nachfolgend nur \u201eDSGVO\u201c genannt), gilt als \u201eVerarbeitung\u201c jeder [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-1191","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Datenschutz - Marina Clavet Coaching<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marina-clavet-coaching.com\/en\/datenschutz\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutz - Marina Clavet Coaching\" \/>\n<meta property=\"og:description\" content=\"Datenschutzerkl\u00e4rung Personenbezogene Daten (nachfolgend zumeist nur \u201eDaten\u201c genannt) werden von uns nur im Rahmen der Erforderlichkeit sowie zum Zwecke der Bereitstellung eines funktionsf\u00e4higen und nutzerfreundlichen Internetauftritts, inklusive seiner Inhalte und der dort angebotenen Leistungen, verarbeitet. Gem\u00e4\u00df Art. 4 Ziffer 1. der Verordnung (EU) 2016\/679, also der Datenschutz-Grundverordnung (nachfolgend nur \u201eDSGVO\u201c genannt), gilt als \u201eVerarbeitung\u201c jeder [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marina-clavet-coaching.com\/en\/datenschutz\/\" \/>\n<meta property=\"og:site_name\" content=\"Marina Clavet Coaching\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marina-clavet-coaching.com\\\/en\\\/datenschutz\\\/\",\"url\":\"https:\\\/\\\/marina-clavet-coaching.com\\\/en\\\/datenschutz\\\/\",\"name\":\"Datenschutz - Marina Clavet Coaching\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marina-clavet-coaching.com\\\/#website\"},\"datePublished\":\"2024-03-14T15:59:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/marina-clavet-coaching.com\\\/en\\\/datenschutz\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/marina-clavet-coaching.com\\\/en\\\/datenschutz\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/marina-clavet-coaching.com\\\/en\\\/datenschutz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/marina-clavet-coaching.com\\\/en\\\/home-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marina-clavet-coaching.com\\\/#website\",\"url\":\"https:\\\/\\\/marina-clavet-coaching.com\\\/\",\"name\":\"Marina Clavet Coaching\",\"description\":\"Coach professionnelle\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marina-clavet-coaching.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutz - Marina Clavet Coaching","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marina-clavet-coaching.com\/en\/datenschutz\/","og_locale":"en_US","og_type":"article","og_title":"Datenschutz - Marina Clavet Coaching","og_description":"Datenschutzerkl\u00e4rung Personenbezogene Daten (nachfolgend zumeist nur \u201eDaten\u201c genannt) werden von uns nur im Rahmen der Erforderlichkeit sowie zum Zwecke der Bereitstellung eines funktionsf\u00e4higen und nutzerfreundlichen Internetauftritts, inklusive seiner Inhalte und der dort angebotenen Leistungen, verarbeitet. Gem\u00e4\u00df Art. 4 Ziffer 1. der Verordnung (EU) 2016\/679, also der Datenschutz-Grundverordnung (nachfolgend nur \u201eDSGVO\u201c genannt), gilt als \u201eVerarbeitung\u201c jeder [&hellip;]","og_url":"https:\/\/marina-clavet-coaching.com\/en\/datenschutz\/","og_site_name":"Marina Clavet Coaching","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"15 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/marina-clavet-coaching.com\/en\/datenschutz\/","url":"https:\/\/marina-clavet-coaching.com\/en\/datenschutz\/","name":"Datenschutz - Marina Clavet Coaching","isPartOf":{"@id":"https:\/\/marina-clavet-coaching.com\/#website"},"datePublished":"2024-03-14T15:59:34+00:00","breadcrumb":{"@id":"https:\/\/marina-clavet-coaching.com\/en\/datenschutz\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marina-clavet-coaching.com\/en\/datenschutz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/marina-clavet-coaching.com\/en\/datenschutz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/marina-clavet-coaching.com\/en\/home-2\/"},{"@type":"ListItem","position":2,"name":"Datenschutz"}]},{"@type":"WebSite","@id":"https:\/\/marina-clavet-coaching.com\/#website","url":"https:\/\/marina-clavet-coaching.com\/","name":"Marina Clavet Coaching","description":"Coach professionnelle","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marina-clavet-coaching.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/marina-clavet-coaching.com\/en\/wp-json\/wp\/v2\/pages\/1191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marina-clavet-coaching.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/marina-clavet-coaching.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/marina-clavet-coaching.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/marina-clavet-coaching.com\/en\/wp-json\/wp\/v2\/comments?post=1191"}],"version-history":[{"count":0,"href":"https:\/\/marina-clavet-coaching.com\/en\/wp-json\/wp\/v2\/pages\/1191\/revisions"}],"wp:attachment":[{"href":"https:\/\/marina-clavet-coaching.com\/en\/wp-json\/wp\/v2\/media?parent=1191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}